{"id":10319,"date":"2025-03-21T14:07:22","date_gmt":"2025-03-21T13:07:22","guid":{"rendered":"https:\/\/nutzfahrzeugtechnik.org\/vehicles\/man\/tgx\/"},"modified":"2025-03-21T14:07:22","modified_gmt":"2025-03-21T13:07:22","slug":"tgx","status":"publish","type":"page","link":"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/","title":{"rendered":"TGX"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":10313,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10319","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rotachain automatic snow chains for MAN TGX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rotachain automatic snow chains for MAN TGX\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/\" \/>\n<meta property=\"og:site_name\" content=\"Schleuderketten Rotationsketten\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/\",\"url\":\"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/\",\"name\":\"Rotachain automatic snow chains for MAN TGX\",\"isPartOf\":{\"@id\":\"https:\/\/www.anfahrhilfe.com\/#website\"},\"datePublished\":\"2025-03-21T13:07:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/rotationskette.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equippable vehicles\",\"item\":\"https:\/\/rotachain.com\/en\/vehicles\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MAN\",\"item\":\"https:\/\/schleuderketten.com\/en\/vehicles\/man\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"TGX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.anfahrhilfe.com\/#website\",\"url\":\"https:\/\/www.anfahrhilfe.com\/\",\"name\":\"Schleuderketten Rotationsketten\",\"description\":\"Rotachain f\u00fcr Nutzfahrzeuge wie MAN, Mercedes Benz, Iveco, Scania, Renault, DAF\",\"publisher\":{\"@id\":\"https:\/\/www.anfahrhilfe.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.anfahrhilfe.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.anfahrhilfe.com\/#organization\",\"name\":\"Schleuderketten Rotationsketten\",\"url\":\"https:\/\/www.anfahrhilfe.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png\",\"contentUrl\":\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png\",\"width\":423,\"height\":256,\"caption\":\"Schleuderketten Rotationsketten\"},\"image\":{\"@id\":\"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rotachain automatic snow chains for MAN TGX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/","og_locale":"en_US","og_type":"article","og_title":"Rotachain automatic snow chains for MAN TGX","og_url":"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/","og_site_name":"Schleuderketten Rotationsketten","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/","url":"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/","name":"Rotachain automatic snow chains for MAN TGX","isPartOf":{"@id":"https:\/\/www.anfahrhilfe.com\/#website"},"datePublished":"2025-03-21T13:07:22+00:00","breadcrumb":{"@id":"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schleuderketten.com\/en\/vehicles\/man\/tgx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rotationskette.com\/en\/"},{"@type":"ListItem","position":2,"name":"Equippable vehicles","item":"https:\/\/rotachain.com\/en\/vehicles\/"},{"@type":"ListItem","position":3,"name":"MAN","item":"https:\/\/schleuderketten.com\/en\/vehicles\/man\/"},{"@type":"ListItem","position":4,"name":"TGX"}]},{"@type":"WebSite","@id":"https:\/\/www.anfahrhilfe.com\/#website","url":"https:\/\/www.anfahrhilfe.com\/","name":"Schleuderketten Rotationsketten","description":"Rotachain f\u00fcr Nutzfahrzeuge wie MAN, Mercedes Benz, Iveco, Scania, Renault, DAF","publisher":{"@id":"https:\/\/www.anfahrhilfe.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anfahrhilfe.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.anfahrhilfe.com\/#organization","name":"Schleuderketten Rotationsketten","url":"https:\/\/www.anfahrhilfe.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/","url":"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png","contentUrl":"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png","width":423,"height":256,"caption":"Schleuderketten Rotationsketten"},"image":{"@id":"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/schleuderketten.com\/en\/wp-json\/wp\/v2\/pages\/10319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schleuderketten.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/schleuderketten.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/schleuderketten.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schleuderketten.com\/en\/wp-json\/wp\/v2\/comments?post=10319"}],"version-history":[{"count":0,"href":"https:\/\/schleuderketten.com\/en\/wp-json\/wp\/v2\/pages\/10319\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/schleuderketten.com\/en\/wp-json\/wp\/v2\/pages\/10313"}],"wp:attachment":[{"href":"https:\/\/schleuderketten.com\/en\/wp-json\/wp\/v2\/media?parent=10319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}