{"id":10257,"date":"2025-03-21T14:07:18","date_gmt":"2025-03-21T13:07:18","guid":{"rendered":"https:\/\/nutzfahrzeugtechnik.org\/vehicules\/daf\/cf85\/"},"modified":"2025-03-21T14:07:18","modified_gmt":"2025-03-21T13:07:18","slug":"cf85","status":"publish","type":"page","link":"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/","title":{"rendered":"CF85"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":10242,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10257","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rotachain chai\u0302nages automatiques pour DAF CF85<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rotachain chai\u0302nages automatiques pour DAF CF85\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/\" \/>\n<meta property=\"og:site_name\" content=\"Schleuderketten Rotationsketten\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/\",\"url\":\"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/\",\"name\":\"Rotachain chai\u0302nages automatiques pour DAF CF85\",\"isPartOf\":{\"@id\":\"https:\/\/www.anfahrhilfe.com\/#website\"},\"datePublished\":\"2025-03-21T13:07:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/rotachain.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00e9hicules \u00e9quipables\",\"item\":\"https:\/\/www.rotationsketten.de\/fr\/vehicules\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DAF\",\"item\":\"https:\/\/www.schleuderketten.com\/fr\/vehicules\/daf\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"CF85\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.anfahrhilfe.com\/#website\",\"url\":\"https:\/\/www.anfahrhilfe.com\/\",\"name\":\"Schleuderketten Rotationsketten\",\"description\":\"Rotachain f\u00fcr Nutzfahrzeuge wie MAN, Mercedes Benz, Iveco, Scania, Renault, DAF\",\"publisher\":{\"@id\":\"https:\/\/www.anfahrhilfe.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.anfahrhilfe.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.anfahrhilfe.com\/#organization\",\"name\":\"Schleuderketten Rotationsketten\",\"url\":\"https:\/\/www.anfahrhilfe.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png\",\"contentUrl\":\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png\",\"width\":423,\"height\":256,\"caption\":\"Schleuderketten Rotationsketten\"},\"image\":{\"@id\":\"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rotachain chai\u0302nages automatiques pour DAF CF85","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/","og_locale":"fr_FR","og_type":"article","og_title":"Rotachain chai\u0302nages automatiques pour DAF CF85","og_url":"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/","og_site_name":"Schleuderketten Rotationsketten","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/","url":"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/","name":"Rotachain chai\u0302nages automatiques pour DAF CF85","isPartOf":{"@id":"https:\/\/www.anfahrhilfe.com\/#website"},"datePublished":"2025-03-21T13:07:18+00:00","breadcrumb":{"@id":"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/schleuderketten.com\/fr\/vehicules\/daf\/cf85\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rotachain.com\/fr\/"},{"@type":"ListItem","position":2,"name":"V\u00e9hicules \u00e9quipables","item":"https:\/\/www.rotationsketten.de\/fr\/vehicules\/"},{"@type":"ListItem","position":3,"name":"DAF","item":"https:\/\/www.schleuderketten.com\/fr\/vehicules\/daf\/"},{"@type":"ListItem","position":4,"name":"CF85"}]},{"@type":"WebSite","@id":"https:\/\/www.anfahrhilfe.com\/#website","url":"https:\/\/www.anfahrhilfe.com\/","name":"Schleuderketten Rotationsketten","description":"Rotachain f\u00fcr Nutzfahrzeuge wie MAN, Mercedes Benz, Iveco, Scania, Renault, DAF","publisher":{"@id":"https:\/\/www.anfahrhilfe.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anfahrhilfe.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.anfahrhilfe.com\/#organization","name":"Schleuderketten Rotationsketten","url":"https:\/\/www.anfahrhilfe.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/","url":"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png","contentUrl":"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png","width":423,"height":256,"caption":"Schleuderketten Rotationsketten"},"image":{"@id":"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/pages\/10257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/comments?post=10257"}],"version-history":[{"count":0,"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/pages\/10257\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/pages\/10242"}],"wp:attachment":[{"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/media?parent=10257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}