{"id":938,"date":"2024-06-05T10:49:48","date_gmt":"2024-06-05T08:49:48","guid":{"rendered":"http:\/\/nutzfahrzeugtechnik.org\/chaines-rotatives-rotachain\/"},"modified":"2025-04-14T17:30:53","modified_gmt":"2025-04-14T15:30:53","slug":"kit-d-installation","status":"publish","type":"page","link":"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/","title":{"rendered":"Kit d&rsquo;installation"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"938\" class=\"elementor elementor-938 elementor-198\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-665eefc e-con-full e-flex e-con e-parent\" data-id=\"665eefc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65a1d9f elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"65a1d9f\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-0170a16 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Un kit enti\u00e8rement pr\u00eat \u00e0 \u00eatre install\u00e9<\/div><div class=\"elementor-slide-description\"><p>Qui vous permet une installation rapide et sans complications.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-3096761 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Un kit enti\u00e8rement pr\u00eat \u00e0 \u00eatre install\u00e9<\/div><div class=\"elementor-slide-description\"><p>Qui vous permet une installation rapide et sans complications.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-99c6025 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Un kit enti\u00e8rement pr\u00eat \u00e0 \u00eatre install\u00e9<\/div><div class=\"elementor-slide-description\"><p>Qui vous permet une installation rapide et sans complications.<\/p>\n<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive pr\u00e9c\u00e9dente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive suivante\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c600214 e-flex e-con-boxed e-con e-parent\" data-id=\"c600214\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fb8f64b e-con-full e-flex e-con e-child\" data-id=\"fb8f64b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c77b5e6 elementor-widget elementor-widget-heading\" data-id=\"c77b5e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kit d'installation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3d042a elementor-fixed elementor-widget elementor-widget-button\" data-id=\"b3d042a\" data-element_type=\"widget\" id=\"scroll-to-top\" data-settings=\"{&quot;_position&quot;:&quot;fixed&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M34.9 289.5l-22.2-22.2c-9.4-9.4-9.4-24.6 0-33.9L207 39c9.4-9.4 24.6-9.4 33.9 0l194.3 194.3c9.4 9.4 9.4 24.6 0 33.9L413 289.4c-9.5 9.5-25 9.3-34.3-.4L264 168.6V456c0 13.3-10.7 24-24 24h-32c-13.3 0-24-10.7-24-24V168.6L69.2 289.1c-9.3 9.8-24.8 10-34.3.4z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df99635 elementor-widget elementor-widget-html\" data-id=\"df99635\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>document.addEventListener(\"DOMContentLoaded\", function() {\n    var button = document.getElementById(\"scroll-to-top\");\n\n    window.addEventListener(\"scroll\", function() {\n        if (window.scrollY > 1200) {\n            button.classList.add(\"visible\");\n        } else {\n            button.classList.remove(\"visible\");\n        }\n    });\n\n    button.addEventListener(\"click\", function() {\n        var newPosition = window.scrollY * 0.4; \/\/ Scrollt um 20% nach oben\n        window.scrollTo({ top: newPosition, behavior: 'smooth' });\n    });\n});\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5f4095 elementor-widget elementor-widget-text-editor\" data-id=\"c5f4095\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Le kit vous fournit toutes les pi\u00e8ces n\u00e9cessaires et les instructions pour une installation facile, vous permettant de <span style=\"font-size: 1rem;\">travailler rapidement et efficacement, sans achats suppl\u00e9mentaires ni pr\u00e9parations.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fc20b5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5fc20b5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/nutzfahrzeugtechnik.org\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous maintenant<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caadc59 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-hotspot\" data-id=\"caadc59\" data-element_type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;98be6c2&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;#1&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/nutzfahrzeugtechnik.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Group-55.svg&quot;,&quot;id&quot;:223},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:52,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;&quot;,&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Add Your Tooltip Text Here&lt;\\\/p&gt;\\n&quot;,&quot;index&quot;:0,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:null},{&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;#1&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/nutzfahrzeugtechnik.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Group-55.svg&quot;,&quot;id&quot;:223},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:89.5,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:51,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;&quot;,&quot;_id&quot;:&quot;718fbfe&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Add Your Tooltip Text Here&lt;\\\/p&gt;\\n&quot;,&quot;index&quot;:1,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:null},{&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;#2&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/nutzfahrzeugtechnik.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Group-56.svg&quot;,&quot;id&quot;:227},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;&quot;,&quot;_id&quot;:&quot;f4cf0f0&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Add Your Tooltip Text Here&lt;\\\/p&gt;\\n&quot;,&quot;hotspot_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;hotspot_custom_size&quot;:&quot;yes&quot;,&quot;index&quot;:2,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:null},{&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;#3&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/nutzfahrzeugtechnik.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Group-57.svg&quot;,&quot;id&quot;:241},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:12.2,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:19,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;&quot;,&quot;_id&quot;:&quot;88e42b9&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Add Your Tooltip Text Here&lt;\\\/p&gt;\\n&quot;,&quot;index&quot;:3,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:null},{&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;#3&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/nutzfahrzeugtechnik.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Group-57.svg&quot;,&quot;id&quot;:241},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:86.7,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:19,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;&quot;,&quot;_id&quot;:&quot;d02fa96&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Add Your Tooltip Text Here&lt;\\\/p&gt;\\n&quot;,&quot;index&quot;:4,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:null}],&quot;tooltip_position&quot;:&quot;top&quot;,&quot;tooltip_trigger&quot;:&quot;click&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-in-out&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"446\" src=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png\" class=\"attachment-large size-large wp-image-3235\" alt=\"\" srcset=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png 1024w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/01\/schleuder-300x167.png 300w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/01\/schleuder-768x428.png 768w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/01\/schleuder.png 1536w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-98be6c2  e-hotspot--position-left e-hotspot--position-top e-hotspot--link e-hotspot--no-tooltip e-hotspot--icon\" href=\"#1\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M40.1456 36.595V27.85H55.3806V68H45.5906V36.595H40.1456Z\" fill=\"white\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t<\/a>\n\n\t\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-718fbfe  e-hotspot--position-left e-hotspot--position-top e-hotspot--link e-hotspot--no-tooltip e-hotspot--icon\" href=\"#1\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M40.1456 36.595V27.85H55.3806V68H45.5906V36.595H40.1456Z\" fill=\"white\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t<\/a>\n\n\t\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-f4cf0f0   e-hotspot--position-top e-hotspot--link e-hotspot--no-tooltip e-hotspot--icon\" href=\"#2\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M35.4346 60.465C36.6812 59.475 37.2496 59.0167 37.1396 59.09C40.7329 56.12 43.5562 53.6817 45.6096 51.775C47.6996 49.8683 49.4596 47.87 50.8896 45.78C52.3196 43.69 53.0346 41.655 53.0346 39.675C53.0346 38.1717 52.6862 36.9983 51.9896 36.155C51.2929 35.3117 50.2479 34.89 48.8546 34.89C47.4612 34.89 46.3612 35.4217 45.5546 36.485C44.7846 37.5117 44.3996 38.9783 44.3996 40.885H35.3246C35.3979 37.7683 36.0579 35.165 37.3046 33.075C38.5879 30.985 40.2562 29.445 42.3096 28.455C44.3996 27.465 46.7096 26.97 49.2396 26.97C53.6029 26.97 56.8846 28.0883 59.0846 30.325C61.3212 32.5617 62.4396 35.4767 62.4396 39.07C62.4396 42.9933 61.1012 46.6417 58.4246 50.015C55.7479 53.3517 52.3379 56.615 48.1946 59.805H63.0446V67.45H35.4346V60.465Z\" fill=\"white\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t<\/a>\n\n\t\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-88e42b9  e-hotspot--position-left e-hotspot--position-top e-hotspot--link e-hotspot--no-tooltip e-hotspot--icon\" href=\"#3\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M35.1546 39.18C35.3013 35.2567 36.5846 32.2317 39.0046 30.105C41.4246 27.9783 44.7063 26.915 48.8496 26.915C51.5996 26.915 53.9463 27.3917 55.8896 28.345C57.8696 29.2983 59.3546 30.6 60.3446 32.25C61.3713 33.9 61.8846 35.7517 61.8846 37.805C61.8846 40.225 61.2796 42.205 60.0696 43.745C58.8596 45.2483 57.4479 46.275 55.8346 46.825V47.045C57.9246 47.7417 59.5746 48.8967 60.7846 50.51C61.9946 52.1233 62.5996 54.195 62.5996 56.725C62.5996 58.9983 62.0679 61.015 61.0046 62.775C59.9779 64.4983 58.4563 65.855 56.4396 66.845C54.4596 67.835 52.0946 68.33 49.3446 68.33C44.9446 68.33 41.4246 67.2483 38.7846 65.085C36.1813 62.9217 34.8063 59.6583 34.6596 55.295H43.7896C43.8263 56.9083 44.2846 58.1917 45.1646 59.145C46.0446 60.0617 47.3279 60.52 49.0146 60.52C50.4446 60.52 51.5446 60.1167 52.3146 59.31C53.1213 58.4667 53.5246 57.3667 53.5246 56.01C53.5246 54.25 52.9563 52.985 51.8196 52.215C50.7196 51.4083 48.9413 51.005 46.4846 51.005H44.7246V43.36H46.4846C48.3546 43.36 49.8579 43.0483 50.9946 42.425C52.1679 41.765 52.7546 40.61 52.7546 38.96C52.7546 37.64 52.3879 36.6133 51.6546 35.88C50.9213 35.1467 49.9129 34.78 48.6296 34.78C47.2363 34.78 46.1913 35.2017 45.4946 36.045C44.8346 36.8883 44.4496 37.9333 44.3396 39.18H35.1546Z\" fill=\"white\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t<\/a>\n\n\t\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-d02fa96  e-hotspot--position-left e-hotspot--position-top e-hotspot--link e-hotspot--no-tooltip e-hotspot--icon\" href=\"#3\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M35.1546 39.18C35.3013 35.2567 36.5846 32.2317 39.0046 30.105C41.4246 27.9783 44.7063 26.915 48.8496 26.915C51.5996 26.915 53.9463 27.3917 55.8896 28.345C57.8696 29.2983 59.3546 30.6 60.3446 32.25C61.3713 33.9 61.8846 35.7517 61.8846 37.805C61.8846 40.225 61.2796 42.205 60.0696 43.745C58.8596 45.2483 57.4479 46.275 55.8346 46.825V47.045C57.9246 47.7417 59.5746 48.8967 60.7846 50.51C61.9946 52.1233 62.5996 54.195 62.5996 56.725C62.5996 58.9983 62.0679 61.015 61.0046 62.775C59.9779 64.4983 58.4563 65.855 56.4396 66.845C54.4596 67.835 52.0946 68.33 49.3446 68.33C44.9446 68.33 41.4246 67.2483 38.7846 65.085C36.1813 62.9217 34.8063 59.6583 34.6596 55.295H43.7896C43.8263 56.9083 44.2846 58.1917 45.1646 59.145C46.0446 60.0617 47.3279 60.52 49.0146 60.52C50.4446 60.52 51.5446 60.1167 52.3146 59.31C53.1213 58.4667 53.5246 57.3667 53.5246 56.01C53.5246 54.25 52.9563 52.985 51.8196 52.215C50.7196 51.4083 48.9413 51.005 46.4846 51.005H44.7246V43.36H46.4846C48.3546 43.36 49.8579 43.0483 50.9946 42.425C52.1679 41.765 52.7546 40.61 52.7546 38.96C52.7546 37.64 52.3879 36.6133 51.6546 35.88C50.9213 35.1467 49.9129 34.78 48.6296 34.78C47.2363 34.78 46.1913 35.2017 45.4946 36.045C44.8346 36.8883 44.4496 37.9333 44.3396 39.18H35.1546Z\" fill=\"white\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t<\/a>\n\n\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2366b4 elementor-widget elementor-widget-menu-anchor\" data-id=\"a2366b4\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"1\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2595df elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-menu-anchor\" data-id=\"a2595df\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"eins\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ef1034 elementor-hidden-desktop elementor-widget elementor-widget-hotspot\" data-id=\"4ef1034\" data-element_type=\"widget\" data-settings=\"{&quot;hotspot&quot;:[{&quot;_id&quot;:&quot;98be6c2&quot;,&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;#eins&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/nutzfahrzeugtechnik.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Group-55.svg&quot;,&quot;id&quot;:223},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:52,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;&quot;,&quot;hotspot_custom_size&quot;:&quot;&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Add Your Tooltip Text Here&lt;\\\/p&gt;\\n&quot;,&quot;index&quot;:0,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:null},{&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;#eins&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/nutzfahrzeugtechnik.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Group-55.svg&quot;,&quot;id&quot;:223},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:89.5,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:51,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;&quot;,&quot;_id&quot;:&quot;718fbfe&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Add Your Tooltip Text Here&lt;\\\/p&gt;\\n&quot;,&quot;index&quot;:1,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:null},{&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;#zwei&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/nutzfahrzeugtechnik.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Group-56.svg&quot;,&quot;id&quot;:227},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;&quot;,&quot;_id&quot;:&quot;f4cf0f0&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Add Your Tooltip Text Here&lt;\\\/p&gt;\\n&quot;,&quot;hotspot_offset_x_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;hotspot_offset_x_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;hotspot_offset_y_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;index&quot;:2,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:null},{&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;#drei&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/nutzfahrzeugtechnik.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Group-57.svg&quot;,&quot;id&quot;:241},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:12.2,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:19,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;&quot;,&quot;_id&quot;:&quot;88e42b9&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Add Your Tooltip Text Here&lt;\\\/p&gt;\\n&quot;,&quot;index&quot;:3,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:null},{&quot;hotspot_link&quot;:{&quot;url&quot;:&quot;#drei&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;},&quot;hotspot_icon&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/nutzfahrzeugtechnik.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Group-57.svg&quot;,&quot;id&quot;:241},&quot;library&quot;:&quot;svg&quot;},&quot;hotspot_offset_x&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:86.7,&quot;sizes&quot;:[]},&quot;hotspot_offset_y&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:19,&quot;sizes&quot;:[]},&quot;hotspot_tooltip_position&quot;:&quot;&quot;,&quot;_id&quot;:&quot;d02fa96&quot;,&quot;hotspot_tooltip_content&quot;:&quot;&lt;p&gt;Add Your Tooltip Text Here&lt;\\\/p&gt;\\n&quot;,&quot;index&quot;:4,&quot;__dynamic__&quot;:null,&quot;hotspot_label&quot;:&quot;&quot;,&quot;hotspot_custom_size&quot;:&quot;no&quot;,&quot;hotspot_horizontal&quot;:&quot;left&quot;,&quot;hotspot_vertical&quot;:&quot;top&quot;,&quot;hotspot_position&quot;:null}],&quot;hotspot_sequenced_animation&quot;:&quot;yes&quot;,&quot;hotspot_sequenced_animation_duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2483,&quot;sizes&quot;:[]},&quot;tooltip_position&quot;:&quot;top&quot;,&quot;tooltip_trigger&quot;:&quot;click&quot;,&quot;tooltip_animation&quot;:&quot;e-hotspot--fade-in-out&quot;}\" data-widget_type=\"hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"446\" src=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png\" class=\"attachment-large size-large wp-image-3235\" alt=\"\" srcset=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png 1024w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/01\/schleuder-300x167.png 300w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/01\/schleuder-768x428.png 768w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/01\/schleuder.png 1536w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-98be6c2 e-hotspot--sequenced e-hotspot--position-left e-hotspot--position-top e-hotspot--link e-hotspot--no-tooltip e-hotspot--icon\" href=\"#eins\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M40.1456 36.595V27.85H55.3806V68H45.5906V36.595H40.1456Z\" fill=\"white\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t<\/a>\n\n\t\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-718fbfe e-hotspot--sequenced e-hotspot--position-left e-hotspot--position-top e-hotspot--link e-hotspot--no-tooltip e-hotspot--icon\" href=\"#eins\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M40.1456 36.595V27.85H55.3806V68H45.5906V36.595H40.1456Z\" fill=\"white\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t<\/a>\n\n\t\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-f4cf0f0 e-hotspot--sequenced  e-hotspot--position-top e-hotspot--link e-hotspot--no-tooltip e-hotspot--icon\" href=\"#zwei\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M35.4346 60.465C36.6812 59.475 37.2496 59.0167 37.1396 59.09C40.7329 56.12 43.5562 53.6817 45.6096 51.775C47.6996 49.8683 49.4596 47.87 50.8896 45.78C52.3196 43.69 53.0346 41.655 53.0346 39.675C53.0346 38.1717 52.6862 36.9983 51.9896 36.155C51.2929 35.3117 50.2479 34.89 48.8546 34.89C47.4612 34.89 46.3612 35.4217 45.5546 36.485C44.7846 37.5117 44.3996 38.9783 44.3996 40.885H35.3246C35.3979 37.7683 36.0579 35.165 37.3046 33.075C38.5879 30.985 40.2562 29.445 42.3096 28.455C44.3996 27.465 46.7096 26.97 49.2396 26.97C53.6029 26.97 56.8846 28.0883 59.0846 30.325C61.3212 32.5617 62.4396 35.4767 62.4396 39.07C62.4396 42.9933 61.1012 46.6417 58.4246 50.015C55.7479 53.3517 52.3379 56.615 48.1946 59.805H63.0446V67.45H35.4346V60.465Z\" fill=\"white\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t<\/a>\n\n\t\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-88e42b9 e-hotspot--sequenced e-hotspot--position-left e-hotspot--position-top e-hotspot--link e-hotspot--no-tooltip e-hotspot--icon\" href=\"#drei\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M35.1546 39.18C35.3013 35.2567 36.5846 32.2317 39.0046 30.105C41.4246 27.9783 44.7063 26.915 48.8496 26.915C51.5996 26.915 53.9463 27.3917 55.8896 28.345C57.8696 29.2983 59.3546 30.6 60.3446 32.25C61.3713 33.9 61.8846 35.7517 61.8846 37.805C61.8846 40.225 61.2796 42.205 60.0696 43.745C58.8596 45.2483 57.4479 46.275 55.8346 46.825V47.045C57.9246 47.7417 59.5746 48.8967 60.7846 50.51C61.9946 52.1233 62.5996 54.195 62.5996 56.725C62.5996 58.9983 62.0679 61.015 61.0046 62.775C59.9779 64.4983 58.4563 65.855 56.4396 66.845C54.4596 67.835 52.0946 68.33 49.3446 68.33C44.9446 68.33 41.4246 67.2483 38.7846 65.085C36.1813 62.9217 34.8063 59.6583 34.6596 55.295H43.7896C43.8263 56.9083 44.2846 58.1917 45.1646 59.145C46.0446 60.0617 47.3279 60.52 49.0146 60.52C50.4446 60.52 51.5446 60.1167 52.3146 59.31C53.1213 58.4667 53.5246 57.3667 53.5246 56.01C53.5246 54.25 52.9563 52.985 51.8196 52.215C50.7196 51.4083 48.9413 51.005 46.4846 51.005H44.7246V43.36H46.4846C48.3546 43.36 49.8579 43.0483 50.9946 42.425C52.1679 41.765 52.7546 40.61 52.7546 38.96C52.7546 37.64 52.3879 36.6133 51.6546 35.88C50.9213 35.1467 49.9129 34.78 48.6296 34.78C47.2363 34.78 46.1913 35.2017 45.4946 36.045C44.8346 36.8883 44.4496 37.9333 44.3396 39.18H35.1546Z\" fill=\"white\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t<\/a>\n\n\t\n\t\t\t\t\t\t<a class=\"e-hotspot elementor-repeater-item-d02fa96 e-hotspot--sequenced e-hotspot--position-left e-hotspot--position-top e-hotspot--link e-hotspot--no-tooltip e-hotspot--icon\" href=\"#drei\">\n\n\t\t\t\t\t\t\t\t<div class=\"e-hotspot__button \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-hotspot__icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M35.1546 39.18C35.3013 35.2567 36.5846 32.2317 39.0046 30.105C41.4246 27.9783 44.7063 26.915 48.8496 26.915C51.5996 26.915 53.9463 27.3917 55.8896 28.345C57.8696 29.2983 59.3546 30.6 60.3446 32.25C61.3713 33.9 61.8846 35.7517 61.8846 37.805C61.8846 40.225 61.2796 42.205 60.0696 43.745C58.8596 45.2483 57.4479 46.275 55.8346 46.825V47.045C57.9246 47.7417 59.5746 48.8967 60.7846 50.51C61.9946 52.1233 62.5996 54.195 62.5996 56.725C62.5996 58.9983 62.0679 61.015 61.0046 62.775C59.9779 64.4983 58.4563 65.855 56.4396 66.845C54.4596 67.835 52.0946 68.33 49.3446 68.33C44.9446 68.33 41.4246 67.2483 38.7846 65.085C36.1813 62.9217 34.8063 59.6583 34.6596 55.295H43.7896C43.8263 56.9083 44.2846 58.1917 45.1646 59.145C46.0446 60.0617 47.3279 60.52 49.0146 60.52C50.4446 60.52 51.5446 60.1167 52.3146 59.31C53.1213 58.4667 53.5246 57.3667 53.5246 56.01C53.5246 54.25 52.9563 52.985 51.8196 52.215C50.7196 51.4083 48.9413 51.005 46.4846 51.005H44.7246V43.36H46.4846C48.3546 43.36 49.8579 43.0483 50.9946 42.425C52.1679 41.765 52.7546 40.61 52.7546 38.96C52.7546 37.64 52.3879 36.6133 51.6546 35.88C50.9213 35.1467 49.9129 34.78 48.6296 34.78C47.2363 34.78 46.1913 35.2017 45.4946 36.045C44.8346 36.8883 44.4496 37.9333 44.3396 39.18H35.1546Z\" fill=\"white\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\t\t\t<\/a>\n\n\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bb41a0 e-flex e-con-boxed e-con e-parent\" data-id=\"3bb41a0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-923e013 e-con-full e-flex e-con e-child\" data-id=\"923e013\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7315d9 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f7315d9\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M40.1456 36.595V27.85H55.3806V68H45.5906V36.595H40.1456Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43dbe1e elementor-widget elementor-widget-heading\" data-id=\"43dbe1e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cylindre d\u2018entrA\u00eenement<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49d92a6 elementor-hidden-mobile elementor-hidden-tablet elementor-widget elementor-widget-menu-anchor\" data-id=\"49d92a6\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"2\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95a1656 elementor-widget elementor-widget-text-editor\" data-id=\"95a1656\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre unit\u00e9 de base Rotachain se distingue par un entra\u00eenement rotatif robuste qui r\u00e9siste aux conditions environnementales les plus difficiles. La protection contre la corrosion garantit une longue dur\u00e9e de vie, tandis que la faible hauteur de construction est rendue possible par un design compact. <\/p><p>Cette conception permet aux v\u00e9hicules d\u2018\u00eatre facilement \u00e9quip\u00e9s de pneus de taille basse et convient \u00e9galement aux v\u00e9hicules de la classe fourgonnette tels que Mercedes-Benz Sprinter, Iveco Daily, VW Crafter, etc.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f1031a e-con-full e-flex e-con e-child\" data-id=\"7f1031a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd61b20 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"dd61b20\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"731\" height=\"1024\" src=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/Grundgeraet_gesaeubert-731x1024.jpg\" class=\"attachment-large size-large wp-image-8249\" alt=\"\" srcset=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/Grundgeraet_gesaeubert-731x1024.jpg 731w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/Grundgeraet_gesaeubert-214x300.jpg 214w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/Grundgeraet_gesaeubert-768x1076.jpg 768w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/Grundgeraet_gesaeubert-1097x1536.jpg 1097w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/Grundgeraet_gesaeubert.jpg 1425w\" sizes=\"(max-width: 731px) 100vw, 731px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0497e66 elementor-hidden-desktop elementor-hidden-tablet elementor-absolute elementor-widget elementor-widget-menu-anchor\" data-id=\"0497e66\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"zwei\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e08e058 elementor-widget__width-initial elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e08e058\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"316\" viewBox=\"0 0 58 316\" fill=\"none\"><rect width=\"58\" height=\"316\" fill=\"#164194\"><\/rect><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a6d4013 e-flex e-con-boxed e-con e-parent\" data-id=\"a6d4013\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-08075da e-con-full e-flex e-con e-child\" data-id=\"08075da\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ac96b4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0ac96b4\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M35.4346 60.465C36.6812 59.475 37.2496 59.0167 37.1396 59.09C40.7329 56.12 43.5562 53.6817 45.6096 51.775C47.6996 49.8683 49.4596 47.87 50.8896 45.78C52.3196 43.69 53.0346 41.655 53.0346 39.675C53.0346 38.1717 52.6862 36.9983 51.9896 36.155C51.2929 35.3117 50.2479 34.89 48.8546 34.89C47.4612 34.89 46.3612 35.4217 45.5546 36.485C44.7846 37.5117 44.3996 38.9783 44.3996 40.885H35.3246C35.3979 37.7683 36.0579 35.165 37.3046 33.075C38.5879 30.985 40.2562 29.445 42.3096 28.455C44.3996 27.465 46.7096 26.97 49.2396 26.97C53.6029 26.97 56.8846 28.0883 59.0846 30.325C61.3212 32.5617 62.4396 35.4767 62.4396 39.07C62.4396 42.9933 61.1012 46.6417 58.4246 50.015C55.7479 53.3517 52.3379 56.615 48.1946 59.805H63.0446V67.45H35.4346V60.465Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f70da1 elementor-widget elementor-widget-heading\" data-id=\"0f70da1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kit support<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c1746f elementor-widget elementor-widget-text-editor\" data-id=\"7c1746f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos kits d&rsquo;adaptateurs offrent une qualit\u00e9 et une durabilit\u00e9 exceptionnelles. <br>Gr\u00e2ce \u00e0 des mat\u00e9riaux de haute qualit\u00e9 et une protection efficace contre la corrosion, nous garantissons la stabilit\u00e9 et une longue dur\u00e9e de vie dans tous les domaines d&rsquo;application. L&rsquo;installation est facile gr\u00e2ce \u00e0 des pi\u00e8ces de montage sur mesure, sp\u00e9cifiques \u00e0 chaque v\u00e9hicule, et nos kits d&rsquo;adaptateurs contiennent des composants suppl\u00e9mentaires tels que des conduites d&rsquo;air, des c\u00e2bles et une bo\u00eete de vannes de commande. De plus, un manuel d&rsquo;instructions d\u00e9taill\u00e9 et en couleur assure une installation sans accroc !   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de734d5 e-con-full e-flex e-con e-child\" data-id=\"de734d5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41c60c5 elementor-hidden-mobile elementor-widget elementor-widget-menu-anchor\" data-id=\"41c60c5\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"3\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1f47b1 elementor-widget elementor-widget-text-editor\" data-id=\"a1f47b1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&rsquo;innovant joint \u00e0 rotule int\u00e9gr\u00e9 dans le bras permet un ajustement optimal de la roue dent\u00e9e sur le pneu. Avec un r\u00e9glage continu dans une plage de +\/- 12\u00b0, il offre des possibilit\u00e9s d&rsquo;adaptation maximales. Sa conception ultra-plate am\u00e9liore l&rsquo;espace disponible, tandis que le montage se fait rapidement et sans complications.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5525c44 e-con-full e-flex e-con e-child\" data-id=\"5525c44\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-238e00a elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"238e00a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"717\" src=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/schleuerkette-einzelteile-neu-1024x918.jpg\" class=\"attachment-large size-large wp-image-3549\" alt=\"\" srcset=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/schleuerkette-einzelteile-neu-1024x918.jpg 1024w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/schleuerkette-einzelteile-neu-300x269.jpg 300w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/schleuerkette-einzelteile-neu-768x689.jpg 768w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/schleuerkette-einzelteile-neu-1536x1378.jpg 1536w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2025\/02\/schleuerkette-einzelteile-neu-2048x1837.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aef7731 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"aef7731\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"554\" src=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/11\/Ansicht-Armlagerung-1024x709.jpg\" class=\"attachment-large size-large wp-image-2191\" alt=\"\" srcset=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/11\/Ansicht-Armlagerung-1024x709.jpg 1024w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/11\/Ansicht-Armlagerung-300x208.jpg 300w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/11\/Ansicht-Armlagerung-768x532.jpg 768w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/11\/Ansicht-Armlagerung-1536x1063.jpg 1536w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/11\/Ansicht-Armlagerung-2048x1418.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f290f0e e-con-full e-flex e-con e-child\" data-id=\"f290f0e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f33877b elementor-widget elementor-widget-heading\" data-id=\"f33877b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rotule integr\u00e9e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0edb883 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-menu-anchor\" data-id=\"0edb883\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"drei\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6c3c4e e-flex e-con-boxed e-con e-parent\" data-id=\"f6c3c4e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0a2a679 e-con-full e-flex e-con e-child\" data-id=\"0a2a679\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-104fdfd elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"104fdfd\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M35.1546 39.18C35.3013 35.2567 36.5846 32.2317 39.0046 30.105C41.4246 27.9783 44.7063 26.915 48.8496 26.915C51.5996 26.915 53.9463 27.3917 55.8896 28.345C57.8696 29.2983 59.3546 30.6 60.3446 32.25C61.3713 33.9 61.8846 35.7517 61.8846 37.805C61.8846 40.225 61.2796 42.205 60.0696 43.745C58.8596 45.2483 57.4479 46.275 55.8346 46.825V47.045C57.9246 47.7417 59.5746 48.8967 60.7846 50.51C61.9946 52.1233 62.5996 54.195 62.5996 56.725C62.5996 58.9983 62.0679 61.015 61.0046 62.775C59.9779 64.4983 58.4563 65.855 56.4396 66.845C54.4596 67.835 52.0946 68.33 49.3446 68.33C44.9446 68.33 41.4246 67.2483 38.7846 65.085C36.1813 62.9217 34.8063 59.6583 34.6596 55.295H43.7896C43.8263 56.9083 44.2846 58.1917 45.1646 59.145C46.0446 60.0617 47.3279 60.52 49.0146 60.52C50.4446 60.52 51.5446 60.1167 52.3146 59.31C53.1213 58.4667 53.5246 57.3667 53.5246 56.01C53.5246 54.25 52.9563 52.985 51.8196 52.215C50.7196 51.4083 48.9413 51.005 46.4846 51.005H44.7246V43.36H46.4846C48.3546 43.36 49.8579 43.0483 50.9946 42.425C52.1679 41.765 52.7546 40.61 52.7546 38.96C52.7546 37.64 52.3879 36.6133 51.6546 35.88C50.9213 35.1467 49.9129 34.78 48.6296 34.78C47.2363 34.78 46.1913 35.2017 45.4946 36.045C44.8346 36.8883 44.4496 37.9333 44.3396 39.18H35.1546Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba85954 elementor-widget elementor-widget-heading\" data-id=\"ba85954\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kit roues de cha\u00eenes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-058dfb5 elementor-widget elementor-widget-text-editor\" data-id=\"058dfb5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre kit de roues dent\u00e9es Rotachain est disponible en deux variantes, avec une roue dent\u00e9e \u00e0 12 ou 18 brins, parfaitement adapt\u00e9es \u00e0 diff\u00e9rents domaines d&rsquo;application et tailles de pneus. Il se compose de cha\u00eenes extr\u00eamement robustes et de disques de cha\u00eene rempla\u00e7ables individuellement.  <br>Une caract\u00e9ristique remarquable est la possibilit\u00e9 de regreaser les roulements gr\u00e2ce \u00e0 un raccord de lubrification int\u00e9gr\u00e9, garantissant un entretien facile et une longue dur\u00e9e de vie. Les roulements \u00e0 billes pr\u00e9-graiss\u00e9s en usine assurent un fonctionnement optimal sans effort suppl\u00e9mentaire. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9323f2f elementor-widget elementor-widget-heading\" data-id=\"9323f2f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Graisseur<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3609083 e-con-full ipx-border-box e-flex e-con e-child\" data-id=\"3609083\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea0cece elementor-widget elementor-widget-menu-anchor\" data-id=\"ea0cece\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"4\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dfda06 elementor-widget elementor-widget-image\" data-id=\"3dfda06\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/08\/Schmiernippel-1-1024x768.jpg\" class=\"attachment-large size-large wp-image-951\" alt=\"\" srcset=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/08\/Schmiernippel-1-1024x768.jpg 1024w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/08\/Schmiernippel-1-300x225.jpg 300w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/08\/Schmiernippel-1-768x576.jpg 768w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/08\/Schmiernippel-1-1536x1152.jpg 1536w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/08\/Schmiernippel-1-2048x1536.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-db866cc e-con-full e-flex e-con e-child\" data-id=\"db866cc\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-404f03d e-con-full ipx-border-box e-flex e-con e-child\" data-id=\"404f03d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15f351b elementor-widget elementor-widget-image\" data-id=\"15f351b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"170\" src=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/06\/kettenrad_12.jpg\" class=\"attachment-large size-large wp-image-164\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c2c1df8 e-con-full ipx-border-box e-flex e-con e-child\" data-id=\"c2c1df8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a4b528 elementor-widget elementor-widget-image\" data-id=\"3a4b528\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"170\" src=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/06\/kettenrad_18.jpg\" class=\"attachment-large size-large wp-image-165\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b920e4 e-flex e-con-boxed e-con e-parent\" data-id=\"3b920e4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b6394d5 e-con-full e-flex e-con e-child\" data-id=\"b6394d5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c3961e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7c3961e\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"95\" height=\"95\" viewBox=\"0 0 95 95\" fill=\"none\"><rect width=\"94.6877\" height=\"94.6877\" rx=\"5\" fill=\"#164194\"><\/rect><path d=\"M33.0842 60.85V53.26L50.4642 28.4H60.9692V52.71H65.4792V60.85H60.9692V68H51.5642V60.85H33.0842ZM52.2242 38.74L42.9842 52.71H52.2242V38.74Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-947898b elementor-widget elementor-widget-heading\" data-id=\"947898b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Interrupteur<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01133dd elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"01133dd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chaque syst\u00e8me Rotachain vous sera livr\u00e9 avec un interrupteur OEM d\u2018origine correspondant au design du tableau de bord. Nous fournissons un sch\u00e9ma de circuit d\u00e9taill\u00e9 et les broches de connexion n\u00e9cessaires pour chaque interrupteur. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13069f0 e-con-full e-flex e-con e-child\" data-id=\"13069f0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-285ecc7 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"285ecc7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"461\" src=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/06\/Schalter_neu-1024x590.jpg\" class=\"attachment-large size-large wp-image-948\" alt=\"\" srcset=\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/06\/Schalter_neu-1024x590.jpg 1024w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/06\/Schalter_neu-300x173.jpg 300w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/06\/Schalter_neu-768x443.jpg 768w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/06\/Schalter_neu-1536x885.jpg 1536w, https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/06\/Schalter_neu-2048x1180.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d417520 elementor-widget__width-initial elementor-absolute elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d417520\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"58\" height=\"316\" viewBox=\"0 0 58 316\" fill=\"none\"><rect width=\"58\" height=\"316\" fill=\"#164194\"><\/rect><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Un kit enti\u00e8rement pr\u00eat \u00e0 \u00eatre install\u00e9 Qui vous permet une installation rapide et sans complications. Un kit enti\u00e8rement pr\u00eat \u00e0 \u00eatre install\u00e9 Qui vous permet une installation rapide et sans complications. Un kit enti\u00e8rement pr\u00eat \u00e0 \u00eatre install\u00e9 Qui vous permet une installation rapide et sans complications. Kit d&rsquo;installation Le kit vous fournit toutes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-938","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rotachain cha\u00eenages automatiques - kit d&#039;installation<\/title>\n<meta name=\"description\" content=\"Rotachain cha\u00eenages automatiques \u2013 Kit d\u2019installation. Un kit enti\u00e8rement pr\u00e9assembl\u00e9 qui permet une installation rapide et simple.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rotachain cha\u00eenages automatiques - kit d&#039;installation\" \/>\n<meta property=\"og:description\" content=\"Rotachain cha\u00eenages automatiques \u2013 Kit d\u2019installation. Un kit enti\u00e8rement pr\u00e9assembl\u00e9 qui permet une installation rapide et simple.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/\" \/>\n<meta property=\"og:site_name\" content=\"Schleuderketten Rotationsketten\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-14T15:30:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nutzfahrzeugtechnik.org\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/\",\"url\":\"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/\",\"name\":\"Rotachain cha\u00eenages automatiques - kit d'installation\",\"isPartOf\":{\"@id\":\"https:\/\/www.anfahrhilfe.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nutzfahrzeugtechnik.org\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png\",\"datePublished\":\"2024-06-05T08:49:48+00:00\",\"dateModified\":\"2025-04-14T15:30:53+00:00\",\"description\":\"Rotachain cha\u00eenages automatiques \u2013 Kit d\u2019installation. Un kit enti\u00e8rement pr\u00e9assembl\u00e9 qui permet une installation rapide et simple.\",\"breadcrumb\":{\"@id\":\"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/#primaryimage\",\"url\":\"https:\/\/nutzfahrzeugtechnik.org\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png\",\"contentUrl\":\"https:\/\/nutzfahrzeugtechnik.org\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/rotachain.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kit d&rsquo;installation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.anfahrhilfe.com\/#website\",\"url\":\"https:\/\/www.anfahrhilfe.com\/\",\"name\":\"Schleuderketten Rotationsketten\",\"description\":\"Rotachain f\u00fcr Nutzfahrzeuge wie MAN, Mercedes Benz, Iveco, Scania, Renault, DAF\",\"publisher\":{\"@id\":\"https:\/\/www.anfahrhilfe.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.anfahrhilfe.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.anfahrhilfe.com\/#organization\",\"name\":\"Schleuderketten Rotationsketten\",\"url\":\"https:\/\/www.anfahrhilfe.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png\",\"contentUrl\":\"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png\",\"width\":423,\"height\":256,\"caption\":\"Schleuderketten Rotationsketten\"},\"image\":{\"@id\":\"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rotachain cha\u00eenages automatiques - kit d'installation","description":"Rotachain cha\u00eenages automatiques \u2013 Kit d\u2019installation. Un kit enti\u00e8rement pr\u00e9assembl\u00e9 qui permet une installation rapide et simple.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/","og_locale":"fr_FR","og_type":"article","og_title":"Rotachain cha\u00eenages automatiques - kit d'installation","og_description":"Rotachain cha\u00eenages automatiques \u2013 Kit d\u2019installation. Un kit enti\u00e8rement pr\u00e9assembl\u00e9 qui permet une installation rapide et simple.","og_url":"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/","og_site_name":"Schleuderketten Rotationsketten","article_modified_time":"2025-04-14T15:30:53+00:00","og_image":[{"url":"https:\/\/nutzfahrzeugtechnik.org\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/","url":"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/","name":"Rotachain cha\u00eenages automatiques - kit d'installation","isPartOf":{"@id":"https:\/\/www.anfahrhilfe.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/#primaryimage"},"image":{"@id":"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/#primaryimage"},"thumbnailUrl":"https:\/\/nutzfahrzeugtechnik.org\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png","datePublished":"2024-06-05T08:49:48+00:00","dateModified":"2025-04-14T15:30:53+00:00","description":"Rotachain cha\u00eenages automatiques \u2013 Kit d\u2019installation. Un kit enti\u00e8rement pr\u00e9assembl\u00e9 qui permet une installation rapide et simple.","breadcrumb":{"@id":"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schleuderketten.com\/fr\/kit-d-installation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/#primaryimage","url":"https:\/\/nutzfahrzeugtechnik.org\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png","contentUrl":"https:\/\/nutzfahrzeugtechnik.org\/wp-content\/uploads\/2025\/01\/schleuder-1024x571.png"},{"@type":"BreadcrumbList","@id":"https:\/\/schleuderketten.com\/fr\/kit-d-installation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rotachain.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Kit d&rsquo;installation"}]},{"@type":"WebSite","@id":"https:\/\/www.anfahrhilfe.com\/#website","url":"https:\/\/www.anfahrhilfe.com\/","name":"Schleuderketten Rotationsketten","description":"Rotachain f\u00fcr Nutzfahrzeuge wie MAN, Mercedes Benz, Iveco, Scania, Renault, DAF","publisher":{"@id":"https:\/\/www.anfahrhilfe.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anfahrhilfe.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.anfahrhilfe.com\/#organization","name":"Schleuderketten Rotationsketten","url":"https:\/\/www.anfahrhilfe.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/","url":"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png","contentUrl":"https:\/\/schleuderketten.com\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png","width":423,"height":256,"caption":"Schleuderketten Rotationsketten"},"image":{"@id":"https:\/\/www.anfahrhilfe.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/pages\/938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/comments?post=938"}],"version-history":[{"count":35,"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/pages\/938\/revisions"}],"predecessor-version":[{"id":11113,"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/pages\/938\/revisions\/11113"}],"wp:attachment":[{"href":"https:\/\/schleuderketten.com\/fr\/wp-json\/wp\/v2\/media?parent=938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}